{"id":26572882,"date":"2026-06-01T06:31:45","date_gmt":"2026-06-01T05:31:45","guid":{"rendered":"https:\/\/www.gitesdomainedelachapelle.com\/?p=26572882"},"modified":"2026-06-15T11:21:04","modified_gmt":"2026-06-15T10:21:04","slug":"rencontre-estivale-chevaux-cagnes-sur-mer-2026","status":"publish","type":"post","link":"https:\/\/www.gitesdomainedelachapelle.com\/en\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/","title":{"rendered":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026 : les Nuits d\u2019\u00c9t\u00e9 \u00e0 l\u2019Hippodrome"},"content":{"rendered":"<p style=\"font-family:sans-serif;font-size:13px;color:#888;margin-bottom:8px\">Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins<\/p>\n\n<p style=\"font-size:15px;color:#444;border-left:3px solid #c9a97a;padding:12px 18px;background:#f5ede2;border-radius:0 8px 8px 0;margin-bottom:14px;line-height:1.9\">You <strong>6 juillet au 22 ao\u00fbt 2026<\/strong>, l&rsquo;Hippodrome de la C\u00f4te d&rsquo;Azur \u00e0 Cagnes-sur-Mer accueille les <strong>Nuits d&rsquo;\u00c9t\u00e9<\/strong> \u2014 <strong>21 soir\u00e9es<\/strong> de courses au trot, concerts, march\u00e9s nocturnes et feux d&rsquo;artifice \u00e0 quelques centaines de m\u00e8tres de la M\u00e9diterran\u00e9e. Une soir\u00e9e familiale et festive \u00e0 <strong>5 \u20ac<\/strong> (gratuit moins de 18 ans), \u00e0 seulement <strong>20 minutes<\/strong> desert <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"color:#a07850\">G\u00eetes Domaine de la Chapelle<\/a>.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Un \u00e9v\u00e9nement pour tous \u2014 bien au-del\u00e0 des courses hippiques<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Les Nuits d&rsquo;\u00c9t\u00e9 ont \u00e9t\u00e9 pens\u00e9es pour s\u00e9duire tous les publics \u2014 n\u00e9ophytes comme passionn\u00e9s. Les <strong>courses au trot<\/strong> constituent le c\u0153ur de la soir\u00e9e, mais l&rsquo;\u00e9v\u00e9nement va bien au-del\u00e0 : march\u00e9s nocturnes, concerts live, feux d&rsquo;artifice, soir\u00e9es \u00e0 th\u00e8me et espaces de restauration transforment l&rsquo;hippodrome en une v\u00e9ritable f\u00eate populaire tout l&rsquo;\u00e9t\u00e9. Le cadre est unique \u2014 l&rsquo;Hippodrome de la C\u00f4te d&rsquo;Azur se situe \u00e0 quelques centaines de m\u00e8tres de la plage, avec un panorama exceptionnel sur la M\u00e9diterran\u00e9e. Le <strong>parking est gratuit<\/strong> et les <strong>moins de 18 ans entrent gratuitement<\/strong> \u2014 l&rsquo;une des meilleures sorties rapport qualit\u00e9\/plaisir de l&rsquo;\u00e9t\u00e9 azur\u00e9en. Pour les noctambules culturels, l&rsquo;hippodrome accueille \u00e9galement les <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-piano-hippodrome-cagnes-sur-mer-2026\/\" style=\"color:#a07850\">Nocturnes du Piano<\/a> du 26 juin au 5 juillet, juste avant les Nuits d&rsquo;\u00c9t\u00e9.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Le programme des soir\u00e9es \u00e0 th\u00e8me 2026<\/h2>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 10px\">Nuits d&rsquo;\u00c9t\u00e9 2026 \u2014 Soir\u00e9es \u00e0 th\u00e8me \u00b7 Hippodrome de Cagnes-sur-Mer<\/p>\n      <table width=\"100%\" cellpadding=\"5\" cellspacing=\"0\" border=\"0\" style=\"font-size:12px;color:#555\">\n        <tr style=\"background:#3b2210;color:#faeeda;font-weight:700\">\n          <td style=\"padding:5px 10px;border-radius:4px 0 0 0;width:28%\">Date<\/td>\n          <td style=\"padding:5px 10px;border-radius:0 4px 0 0\">Soir\u00e9e \u2014 Programme<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>Tous les lundis<\/strong><\/td>\n          <td style=\"padding:6px 10px\">\ud83d\udecd\ufe0f <strong>March\u00e9 nocturne<\/strong> \u00b7 Artisans, cr\u00e9ateurs et produits locaux \u00b7 Ambiance d\u00e9tendue avant les courses<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>8 juillet<\/strong><\/td>\n          <td style=\"padding:6px 10px\">\ud83c\udfc5 <strong>Soir\u00e9e Sport<\/strong> \u00b7 Animations autour de l&rsquo;univers sportif et de la comp\u00e9tition<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>10 juillet<\/strong> \ud83c\udf86<\/td>\n          <td style=\"padding:6px 10px\">\ud83c\udf89 <strong>Hippodrome en F\u00eate<\/strong> \u00b7 Soir\u00e9e phare \u00b7 Animations renforc\u00e9es \u00b7 Feu d&rsquo;artifice en cl\u00f4ture<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>15 juillet<\/strong><\/td>\n          <td style=\"padding:6px 10px\">\ud83d\udc34 <strong>\u00c9quitation des Alpes-Maritimes<\/strong> \u00b7 Hommage aux acteurs du monde \u00e9questre local<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>29 juillet<\/strong> \ud83c\udf86<\/td>\n          <td style=\"padding:6px 10px\">\ud83c\udfb8 <strong>Concert + feu d&rsquo;artifice<\/strong> \u00b7 <strong>The Riviera Rock Busters<\/strong> \u2014 Pop-rock en live \u00b7 Spectacle pyrotechnique en cl\u00f4ture<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>7 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:6px 10px\">\ud83e\udd1d <strong>Race and Care<\/strong> \u00b7 Soir\u00e9e solidarit\u00e9 et partage<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>13 ao\u00fbt<\/strong> \ud83c\udf86<\/td>\n          <td style=\"padding:6px 10px\">\u26a1 <strong>Mythologie<\/strong> \u00b7 Animations th\u00e9matiques \u00b7 Feu d&rsquo;artifice en cl\u00f4ture<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px;white-space:nowrap\"><strong>22 ao\u00fbt<\/strong> \ud83c\udf86<\/td>\n          <td style=\"padding:6px 10px\">\ud83c\udfc6 <strong>Palio de l&rsquo;Amiti\u00e9<\/strong> \u00b7 Grande soir\u00e9e de cl\u00f4ture \u00b7 Animations festives \u00b7 Feu d&rsquo;artifice final<\/td>\n        <\/tr>\n      <\/table>\n      <p style=\"font-size:11px;color:#888;margin:10px 0 0\">Chaque soir\u00e9e : courses au trot + animations + restauration sur place \u00b7 Programme susceptible d&rsquo;\u00e9voluer<\/p>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 6px\">Infos pratiques \u2014 Nuits d&rsquo;\u00c9t\u00e9 2026<\/p>\n      <p style=\"font-size:13px;color:#555;margin:0;line-height:1.9\">\n        <strong>Dates :<\/strong> 6 juillet \u2192 22 ao\u00fbt 2026 \u00b7 21 soir\u00e9es de courses<br>\n        <strong>Lieu :<\/strong> Hippodrome de la C\u00f4te d&rsquo;Azur \u00b7 Cagnes-sur-Mer (06800)<br>\n        <strong>Tarifs :<\/strong> <strong>5 \u20ac<\/strong> en ligne \u00b7 <strong>6 \u20ac<\/strong> sur place \u00b7 <strong>Gratuit moins de 18 ans<\/strong><br>\n        <strong>Parking :<\/strong> Gratuit sur site<br>\n        <strong>Restauration :<\/strong> Sur place tout au long de la soir\u00e9e<br>\n        <strong>Feux d&rsquo;artifice :<\/strong> 10 juillet \u00b7 29 juillet \u00b7 13 ao\u00fbt \u00b7 22 ao\u00fbt (Palio de l&rsquo;Amiti\u00e9)<br>\n        <strong>Acc\u00e8s :<\/strong> Bus depuis Nice \u00b7 Tram + navette depuis le centre de Cagnes<br><strong>Billetterie &amp; infos :<\/strong> <a href=\"https:\/\/www.explorenicecotedazur.com\/evenement\/les-nuits-dete-a-lhippodrome-meeting-hippique-dete\/\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">explorenicecotedazur.com<\/a> \u00b7 <a href=\"https:\/\/cotedazurfrance.fr\/offres\/hippodrome-de-la-cote-dazur-cagnes-sur-mer-fr-3107539\/\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">cotedazurfrance.fr<\/a>\n      <\/p>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Votre base id\u00e9ale \u00e0 20 minutes de l&rsquo;hippodrome<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">\u00c0 <strong>20 minutes de Cagnes-sur-Mer<\/strong>, les <strong>G\u00eetes Domaine de la Chapelle<\/strong> \u00e0 Roquefort-les-Pins sont votre base id\u00e9ale pour les Nuits d&rsquo;\u00c9t\u00e9. Rentrez apr\u00e8s les courses dans votre appartement privatif avec <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/services\/\" style=\"color:#a07850\">piscine chauff\u00e9e et jacuzzi privatifs<\/a> \u2014 la d\u00e9tente garantie apr\u00e8s une soir\u00e9e hippique festive.<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"margin:20px 0;border-collapse:separate;border-spacing:10px\">\n  <tr valign=\"top\">\n    <td width=\"33%\" style=\"background:#ffffff;border:2px solid #c9a97a;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#3b2210;color:#c9a97a;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2605 Le plus luxueux<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf77 L&rsquo;Asti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Grand espace, piscine chauff\u00e9e + jacuzzi haut de gamme<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi haut de gamme en terrasse<br>\u2714 Lit Queen size, clim, WiFi, Netflix<br>\u2714 Grande terrasse, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 Voir L&rsquo;Asti<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2668\ufe0f Vrai spa privatif<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf0a Le Bari<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Spa privatif 3 places sous les \u00e9toiles<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Spa privatif 3 places en terrasse<br>\u2714 Acc\u00e8s piscine chauff\u00e9e couverte<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Nespresso, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/en\/le-bari\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Bari<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\ud83c\udfca Piscine + jacuzzi<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83e\uded2 Le Chianti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Design et contemporain, piscine + jacuzzi<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi privatif en terrasse<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Design contemporain, parking priv\u00e9<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Chianti<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<p style=\"font-family:sans-serif;font-size:13px;background:#f5ede2;border-radius:8px;padding:12px 16px;margin:20px 0\">\n  \ud83c\udfa5 <strong>D\u00e9couvrez les G\u00eetes Domaine de la Chapelle en vid\u00e9o<\/strong> &nbsp;\u00b7&nbsp;\n  <a href=\"https:\/\/www.youtube.com\/watch?v=xb8JsqChTTA\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">\u25b6 Voir la vid\u00e9o<\/a>\n<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#3b2210;border-radius:10px;margin:20px 0\">\n  <tr>\n    <td style=\"padding:20px 24px;text-align:center\">\n      <p style=\"font-size:19px;font-style:italic;color:#faeeda;margin:0 0 8px\">Nuits d&rsquo;\u00c9t\u00e9 \u00e0 20 min \u2014 jacuzzi privatif au retour.<\/p>\n      <p style=\"font-size:13px;color:#c9a97a;margin:0 0 16px\">\u00c0 20 min de Cagnes-sur-Mer \u00b7 Disponibilit\u00e9s en temps r\u00e9el.<\/p>\n      <a href=\"https:\/\/via.eviivo.com\/GtsDmndlChpll06330\" target=\"_blank\" rel=\"noopener\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:10px 24px;font-weight:700;font-family:sans-serif;font-size:13px;text-decoration:none\">\u2726 V\u00e9rifier les disponibilit\u00e9s et r\u00e9server<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Questions fr\u00e9quentes<\/h2>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Les Nuits d&rsquo;\u00c9t\u00e9 sont-elles r\u00e9serv\u00e9es aux amateurs de chevaux ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Non \u2014 l&rsquo;\u00e9v\u00e9nement est pens\u00e9 pour tous les publics. Les courses au trot sont le c\u0153ur du programme, mais concerts, march\u00e9s nocturnes, feux d&rsquo;artifice et soir\u00e9es \u00e0 th\u00e8me en font une vraie f\u00eate estivale accessible \u00e0 tous.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quel est le tarif d&rsquo;entr\u00e9e ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">5 \u20ac en ligne, 6 \u20ac sur place. Gratuit pour tous les moins de 18 ans. Parking gratuit sur site. L&rsquo;une des meilleures soir\u00e9es rapport qualit\u00e9\/plaisir de l&rsquo;\u00e9t\u00e9 sur la C\u00f4te d&rsquo;Azur.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Combien de feux d&rsquo;artifice sont pr\u00e9vus ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Quatre feux d&rsquo;artifice sont programm\u00e9s cet \u00e9t\u00e9 : le 10 juillet (Hippodrome en F\u00eate), le 29 juillet (apr\u00e8s le concert des Riviera Rock Busters), le 13 ao\u00fbt (soir\u00e9e Mythologie) et le 22 ao\u00fbt (Palio de l&rsquo;Amiti\u00e9, soir\u00e9e de cl\u00f4ture).<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Qu&rsquo;est-ce que le Palio de l&rsquo;Amiti\u00e9 ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">La grande soir\u00e9e de cl\u00f4ture des Nuits d&rsquo;\u00c9t\u00e9, le 22 ao\u00fbt \u2014 animations festives en lien avec la tradition du Palio (course \u00e9questre d&rsquo;origine italienne) et feu d&rsquo;artifice final. Le clou de la saison hippique estivale \u00e0 l&rsquo;Hippodrome de la C\u00f4te d&rsquo;Azur.<\/p>\n<\/div>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"border-radius:10px;overflow:hidden;margin:20px 0;font-family:sans-serif\">\n  <tr>\n    <td width=\"170\" valign=\"middle\" style=\"background:#3b2210;padding:20px;text-align:center\">\n      <p style=\"font-size:20px;color:rgba(201,169,122,0.5);margin:0 0 6px\">\ud83d\udc34<\/p>\n      <p style=\"font-size:9px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#c9a97a;margin:0 0 6px;line-height:1.5\">G\u00eetes Domaine de la Chapelle<br>Roquefort-les-Pins<\/p>\n      <p style=\"font-size:14px;font-style:italic;color:#faeeda;margin:0;line-height:1.4\">Votre base \u00e0<br>20 min des<br>Nuits d&rsquo;\u00c9t\u00e9<\/p>\n    <\/td>\n    <td valign=\"middle\" style=\"background:#f5ede2;padding:18px 20px\">\n      <p style=\"font-size:13px;color:#555;margin:0 0 12px;line-height:1.7\">\u00c0 20 minutes de l&rsquo;hippodrome de Cagnes-sur-Mer \u2014 piscine chauff\u00e9e privative et jacuzzi en terrasse pour rentrer se ressourcer apr\u00e8s chaque soir\u00e9e festive.<\/p>\n      <p style=\"margin:0 0 12px\">\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83d\udc34 20 min hippodrome<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udfca Piscine privative<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\u2668\ufe0f Jacuzzi privatif<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;display:inline-block\">\ud83d\ude97 Parking gratuit<\/span>\n      <\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:8px 18px;font-weight:700;font-size:12px;text-decoration:none\">\ud83d\udcc5 Voir nos appartements<\/a>\n      <p style=\"font-size:10px;color:#888;margin:8px 0 0\">\ud83d\udd12 R\u00e9servation s\u00e9curis\u00e9e \u00b7 Confirmation imm\u00e9diate \u00b7 Annulation flexible<\/p>\n    <\/td>\n  <\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins Du 6 juillet au 22 ao\u00fbt 2026, l&rsquo;Hippodrome de la C\u00f4te d&rsquo;Azur \u00e0 Cagnes-sur-Mer accueille les Nuits d&rsquo;\u00c9t\u00e9 \u2014 21 soir\u00e9es de courses au trot, concerts, march\u00e9s nocturnes et feux d&rsquo;artifice \u00e0 quelques centaines de m\u00e8tres de la M\u00e9diterran\u00e9e. Une soir\u00e9e familiale et [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26572884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[128],"tags":[527,530,115,529,528],"dipi_cpt_category":[],"class_list":["post-26572882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-cote-azur","tag-cagnes-sur-mer","tag-courses-hippiques","tag-evenement-cote-dazur","tag-hippodrome-cote-dazur","tag-nuits-dete"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026<\/title>\n<meta name=\"description\" content=\"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gitesdomainedelachapelle.com\/en\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026\" \/>\n<meta property=\"og:description\" content=\"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/en\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00eetes Domaine de la Chapelle\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/patrice.campanella\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T05:31:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T10:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Patrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/\"},\"author\":{\"name\":\"Patrice\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\"},\"headline\":\"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026 : les Nuits d\u2019\u00c9t\u00e9 \u00e0 l\u2019Hippodrome\",\"datePublished\":\"2026-06-01T05:31:45+00:00\",\"dateModified\":\"2026-06-15T10:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/\"},\"wordCount\":937,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp\",\"keywords\":[\"Cagnes-sur-Mer\",\"Courses hippiques\",\"\u00e9v\u00e9nement C\u00f4te d\u2019Azur\",\"Hippodrome C\u00f4te d'Azur\",\"Nuits d'\u00c9t\u00e9\"],\"articleSection\":[\"Evenements sur la C\u00f4te d'Azur\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/\",\"name\":\"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp\",\"datePublished\":\"2026-06-01T05:31:45+00:00\",\"dateModified\":\"2026-06-15T10:21:04+00:00\",\"description\":\"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp\",\"width\":1600,\"height\":1600,\"caption\":\"Courses hippiques, animations et soir\u00e9es festives \u00e0 l'Hippodrome de la C\u00f4te d'Azur.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026 : les Nuits d\u2019\u00c9t\u00e9 \u00e0 l\u2019Hippodrome\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"name\":\"Gites Domaine de la Chapelle\",\"description\":\"G\u00eetes de charme avec piscine chauff\u00e9e et jacuzzi privatif sur la C\u00f4te d\u2019Azur\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\",\"name\":\"Gites Domaine de la Chapelle\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"width\":1024,\"height\":1024,\"caption\":\"Gites Domaine de la Chapelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\",\"name\":\"Patrice\",\"pronouns\":\"nous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"caption\":\"Patrice\"},\"description\":\"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.\",\"sameAs\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\",\"https:\\\/\\\/www.facebook.com\\\/patrice.campanella\\\/\",\"https:\\\/\\\/www.instagram.com\\\/piscine_jacuzzi_cotedazur\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/gitesdomainedelachapelle\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gitesdomainedelachapelle\"],\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/en\\\/author\\\/patrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026","description":"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gitesdomainedelachapelle.com\/en\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/","og_locale":"en_GB","og_type":"article","og_title":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026","og_description":"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.","og_url":"https:\/\/www.gitesdomainedelachapelle.com\/en\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/","og_site_name":"G\u00eetes Domaine de la Chapelle","article_author":"https:\/\/www.facebook.com\/patrice.campanella\/","article_published_time":"2026-06-01T05:31:45+00:00","article_modified_time":"2026-06-15T10:21:04+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp","type":"image\/webp"}],"author":"Patrice","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Patrice","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#article","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/"},"author":{"name":"Patrice","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004"},"headline":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026 : les Nuits d\u2019\u00c9t\u00e9 \u00e0 l\u2019Hippodrome","datePublished":"2026-06-01T05:31:45+00:00","dateModified":"2026-06-15T10:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/"},"wordCount":937,"commentCount":0,"publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp","keywords":["Cagnes-sur-Mer","Courses hippiques","\u00e9v\u00e9nement C\u00f4te d\u2019Azur","Hippodrome C\u00f4te d'Azur","Nuits d'\u00c9t\u00e9"],"articleSection":["Evenements sur la C\u00f4te d'Azur"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/","name":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp","datePublished":"2026-06-01T05:31:45+00:00","dateModified":"2026-06-15T10:21:04+00:00","description":"Rencontre Estivale des Chevaux 2026 \u00e0 Cagnes-sur-Mer : courses hippiques, animations et feux d\u2019artifice \u00e0 l\u2019Hippodrome C\u00f4te d\u2019Azur.","breadcrumb":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#primaryimage","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/nuits-ete-hippodrome-cagnes-sur-mer-courses-chevaux-cote-azur-2026.webp","width":1600,"height":1600,"caption":"Courses hippiques, animations et soir\u00e9es festives \u00e0 l'Hippodrome de la C\u00f4te d'Azur."},{"@type":"BreadcrumbList","@id":"https:\/\/www.gitesdomainedelachapelle.com\/rencontre-estivale-chevaux-cagnes-sur-mer-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gitesdomainedelachapelle.com\/"},{"@type":"ListItem","position":2,"name":"Rencontre Estivale des Chevaux \u00e0 Cagnes-sur-Mer 2026 : les Nuits d\u2019\u00c9t\u00e9 \u00e0 l\u2019Hippodrome"}]},{"@type":"WebSite","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website","url":"https:\/\/www.gitesdomainedelachapelle.com\/","name":"Gites Domaine de la Chapelle","description":"G\u00eetes de charme avec piscine chauff\u00e9e et jacuzzi privatif sur la C\u00f4te d\u2019Azur","publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gitesdomainedelachapelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization","name":"Gites Domaine de la Chapelle","url":"https:\/\/www.gitesdomainedelachapelle.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","width":1024,"height":1024,"caption":"Gites Domaine de la Chapelle"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004","name":"Patrice","pronouns":"nous","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","caption":"Patrice"},"description":"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.","sameAs":["https:\/\/www.gitesdomainedelachapelle.com","https:\/\/www.facebook.com\/patrice.campanella\/","https:\/\/www.instagram.com\/piscine_jacuzzi_cotedazur\/","https:\/\/www.linkedin.com\/in\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\/","https:\/\/fr.pinterest.com\/gitesdomainedelachapelle\/","https:\/\/www.youtube.com\/@gitesdomainedelachapelle"],"url":"https:\/\/www.gitesdomainedelachapelle.com\/en\/author\/patrice\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/posts\/26572882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/comments?post=26572882"}],"version-history":[{"count":4,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/posts\/26572882\/revisions"}],"predecessor-version":[{"id":26573407,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/posts\/26572882\/revisions\/26573407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/media\/26572884"}],"wp:attachment":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/media?parent=26572882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/categories?post=26572882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/tags?post=26572882"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/en\/wp-json\/wp\/v2\/dipi_cpt_category?post=26572882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}