{"id":26572899,"date":"2026-06-01T11:38:18","date_gmt":"2026-06-01T10:38:18","guid":{"rendered":"https:\/\/www.gitesdomainedelachapelle.com\/?p=26572899"},"modified":"2026-06-15T18:39:33","modified_gmt":"2026-06-15T17:39:33","slug":"nocturnes-villa-ephrussi-2026","status":"publish","type":"post","link":"https:\/\/www.gitesdomainedelachapelle.com\/it\/nocturnes-villa-ephrussi-2026\/","title":{"rendered":"Les Nocturnes de la Villa Ephrussi 2026 : soir\u00e9es magiques \u00e0 Saint-Jean-Cap-Ferrat"},"content":{"rendered":"<p style=\"font-family:sans-serif;font-size:13px;color:#888;margin-bottom:8px\">Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins<\/p>\n\n<p style=\"font-size:15px;color:#444;border-left:3px solid #c9a97a;padding:12px 18px;background:#f5ede2;border-radius:0 8px 8px 0;margin-bottom:14px;line-height:1.9\">Du <strong>13 juillet au 25 ao\u00fbt 2026<\/strong>, la <strong>Villa Ephrussi de Rothschild<\/strong> \u00e0 Saint-Jean-Cap-Ferrat ouvre ses portes chaque lundi et mardi soir pour les <strong>Nocturnes de la Villa<\/strong> \u2014 l&rsquo;un des \u00e9v\u00e9nements les plus romanesque et les plus \u00e9l\u00e9gants de la C\u00f4te d&rsquo;Azur. Jardins \u00e0 la fran\u00e7aise illumin\u00e9s aux chandelles, spectacles en plein air face \u00e0 la M\u00e9diterran\u00e9e, musique, danse et gastronomie dans le d\u00e9cor d&rsquo;un palais de la Riviera. \u00c0 <strong>30 minutes<\/strong> des <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"color:#a07850\">G\u00eetes Domaine de la Chapelle<\/a>.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">La Villa Ephrussi de Rothschild \u2014 Un palais de l\u00e9gende sur la presqu&rsquo;\u00eele<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Construite en <strong>1912<\/strong> par la baronne <strong>B\u00e9atrice Ephrussi de Rothschild<\/strong>, la Villa \u00cele-de-France est l&rsquo;un des monuments les plus extraordinaires de la C\u00f4te d&rsquo;Azur. Ce palais de style n\u00e9o-Renaissance est entour\u00e9 de <strong>neuf jardins th\u00e9matiques<\/strong> sur <strong>7 hectares<\/strong> \u2014 jardin \u00e0 la fran\u00e7aise, jardin japonais, jardin espagnol, jardin florentin, jardin de S\u00e8vres, jardin lapidaire, jardin exotique, jardin proven\u00e7al et roseraie. L\u00e9gu\u00e9e \u00e0 l&rsquo;<strong>Acad\u00e9mie des Beaux-Arts de l&rsquo;Institut de France en 1934<\/strong>, elle abrite une collection exceptionnelle d&rsquo;\u0153uvres d&rsquo;art et de mobilier. La nuit tomb\u00e9e, les jardins se transforment \u2014 la lumi\u00e8re des chandelles cr\u00e9e une atmosph\u00e8re hors du temps, absolument unique sur la Riviera. Pour la visiter en journ\u00e9e \u00e9galement, notre guide des <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/plages-saint-jean-cap-ferrat\/\" style=\"color:#a07850\">plages de Saint-Jean-Cap-Ferrat<\/a> vous donnera de bonnes id\u00e9es pour compl\u00e9ter la journ\u00e9e.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">La programmation 2026 \u2014 14 soir\u00e9es de juillet \u00e0 ao\u00fbt<\/h2>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 10px\">Nocturnes de la Villa Ephrussi 2026 \u2014 Lundis et mardis \u00b7 Spectacles \u00e0 21h<\/p>\n      <table width=\"100%\" cellpadding=\"5\" cellspacing=\"0\" border=\"0\" style=\"font-size:12px;color:#555\">\n        <tr style=\"background:#3b2210;color:#faeeda;font-weight:700\">\n          <td style=\"padding:5px 10px;border-radius:4px 0 0 0;width:25%\">Date<\/td>\n          <td style=\"padding:5px 10px;border-radius:0 4px 0 0\">Artiste \/ Spectacle<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>13 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">The Amazing Keystone Big Band<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>14 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Ballet de l&rsquo;Op\u00e9ra Nice C\u00f4te d&rsquo;Azur<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>20 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Lynda Lemay &amp; Jean-F\u00e9lix Lalanne<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>21 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Soyons (pas trop) s\u00e9rieux<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>27 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Malandain Ballet Biarritz<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>28 juillet<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Iris Daverio &amp; Jean-Paul Gasparian<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>3 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Marc Andr\u00e9<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>4 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Trio Stimmung<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>10 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Romain Leleu Sextet<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>11 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Luz Casal<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>17 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Jeanne Cherhal<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>18 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Armando Noguera &amp; \u00c9douard Signolet<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:5px 10px\"><strong>24 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">No\u00e9mi Waysfeld<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:5px 10px\"><strong>25 ao\u00fbt<\/strong><\/td>\n          <td style=\"padding:5px 10px\">Gr\u00e9goire<\/td>\n        <\/tr>\n      <\/table>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Une soir\u00e9e romantique face \u00e0 la M\u00e9diterran\u00e9e<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">D\u00e8s <strong>20h<\/strong>, les jardins de la Villa Ephrussi s&rsquo;illuminent \u00e0 la lueur de centaines de bougies \u2014 les bassins du Jardin \u00e0 la Fran\u00e7aise scintillent, les fontaines murmurent, la brise m\u00e9diterran\u00e9enne porte les effluves des roses et des jasmini\u00e8res. Le spectacle d\u00e9bute \u00e0 <strong>21h<\/strong> et la Villa reste ouverte jusqu&rsquo;\u00e0 <strong>minuit<\/strong> \u2014 le temps de d\u00e9ambuler librement dans les jardins apr\u00e8s le spectacle, d&rsquo;admirer les collections et de profiter du panorama nocturne sur la baie de Villefranche. En cas d&rsquo;intemp\u00e9ries annulant le spectacle, la visite de la Villa et des jardins reste accessible \u2014 et une autre date peut \u00eatre propos\u00e9e. Un cadre id\u00e9al pour d\u00e9couvrir l&rsquo;environnement de la villa avant votre soir\u00e9e, notre guide <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/visiter-eze-cote-azur-village-perche\/\" style=\"color:#a07850\">Visiter \u00c8ze<\/a> sur la corniche toute proche compl\u00e8tera bien la journ\u00e9e.<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 6px\">Infos pratiques \u2014 Nocturnes de la Villa Ephrussi 2026<\/p>\n      <p style=\"font-size:13px;color:#555;margin:0;line-height:1.9\">\n        <strong>Dates :<\/strong> Lundis et mardis du 13 juillet au 25 ao\u00fbt 2026 \u00b7 Ouverture 20h \u00b7 Spectacle 21h \u00b7 Fermeture minuit<br>\n        <strong>Lieu :<\/strong> Villa et Jardins Ephrussi de Rothschild \u00b7 1 avenue Ephrussi de Rothschild \u00b7 06230 Saint-Jean-Cap-Ferrat<br>\n        <strong>Tarifs :<\/strong> Adulte <strong>40 \u20ac<\/strong> \u00b7 Enfant 7-17 ans <strong>20 \u20ac<\/strong> \u00b7 Gratuit moins de 7 ans \u00b7 Formule Nocturne + panier pique-nique <strong>65 \u20ac<\/strong> (r\u00e9servation en ligne uniquement)<br>\n        <strong>Contact :<\/strong> 04 93 01 33 09 \u00b7 <a href=\"https:\/\/www.villa-ephrussi.com\/fr\/nocturnes-villa-2026\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">villa-ephrussi.com<\/a><br>\n        <strong>Acc\u00e8s bus :<\/strong> Ligne 15 depuis Nice (arr\u00eat Passable\/Rothschild, devant la Villa) jusqu&rsquo;\u00e0 23h45<br>\n        <strong>Navette :<\/strong> Service gratuit depuis le boulevard g\u00e9n\u00e9ral de Gaulle<br>\n        <strong>Voiturier :<\/strong> Parking du Centenaire propos\u00e9 par la ville (15 \u20ac)<br>\n        <strong>Intemp\u00e9ries :<\/strong> Si le spectacle est annul\u00e9, visite Villa et jardins maintenue \u00b7 Report sur autre date possible\n      <\/p>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Votre base id\u00e9ale \u00e0 30 minutes de Saint-Jean-Cap-Ferrat<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">\u00c0 <strong>30 minutes de Saint-Jean-Cap-Ferrat<\/strong>, les <strong>G\u00eetes Domaine de la Chapelle<\/strong> \u00e0 Roquefort-les-Pins sont votre base id\u00e9ale pour les Nocturnes. Combinez la soir\u00e9e \u00e0 la Villa Ephrussi avec une nuit dans notre <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/sejour-luxe-detente-riviera\/\" style=\"color:#a07850\">s\u00e9jour luxe et d\u00e9tente sur la Riviera<\/a> \u2014 piscine chauff\u00e9e privative et jacuzzi en terrasse pour rentrer prolonger la magie de la soir\u00e9e.<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"margin:20px 0;border-collapse:separate;border-spacing:10px\">\n  <tr valign=\"top\">\n    <td width=\"33%\" style=\"background:#ffffff;border:2px solid #c9a97a;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#3b2210;color:#c9a97a;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2605 Le plus luxueux<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf77 L&rsquo;Asti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Grand espace, piscine chauff\u00e9e + jacuzzi haut de gamme<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi haut de gamme en terrasse<br>\u2714 Lit Queen size, clim, WiFi, Netflix<br>\u2714 Grande terrasse, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 Voir L&rsquo;Asti<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2668\ufe0f Vrai spa privatif<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf0a Le Bari<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Spa privatif 3 places sous les \u00e9toiles<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Spa privatif 3 places en terrasse<br>\u2714 Acc\u00e8s piscine chauff\u00e9e couverte<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Nespresso, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/en\/le-bari\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Bari<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\ud83c\udfca Piscine + jacuzzi<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83e\uded2 Le Chianti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Design et contemporain, piscine + jacuzzi<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi privatif en terrasse<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Design contemporain, parking priv\u00e9<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Chianti<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<p style=\"font-family:sans-serif;font-size:13px;background:#f5ede2;border-radius:8px;padding:12px 16px;margin:20px 0\">\n  \ud83c\udfa5 <strong>D\u00e9couvrez les G\u00eetes Domaine de la Chapelle en vid\u00e9o<\/strong> &nbsp;\u00b7&nbsp;\n  <a href=\"https:\/\/www.youtube.com\/watch?v=xb8JsqChTTA\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">\u25b6 Voir la vid\u00e9o<\/a>\n<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#3b2210;border-radius:10px;margin:20px 0\">\n  <tr>\n    <td style=\"padding:20px 24px;text-align:center\">\n      <p style=\"font-size:19px;font-style:italic;color:#faeeda;margin:0 0 8px\">Soir\u00e9e \u00e0 la Villa Ephrussi \u2014 jacuzzi privatif au retour.<\/p>\n      <p style=\"font-size:13px;color:#c9a97a;margin:0 0 16px\">\u00c0 30 min de Saint-Jean-Cap-Ferrat \u00b7 Disponibilit\u00e9s en temps r\u00e9el.<\/p>\n      <a href=\"https:\/\/via.eviivo.com\/GtsDmndlChpll06330\" target=\"_blank\" rel=\"noopener\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:10px 24px;font-weight:700;font-family:sans-serif;font-size:13px;text-decoration:none\">\u2726 V\u00e9rifier les disponibilit\u00e9s et r\u00e9server<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Questions fr\u00e9quentes<\/h2>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">O\u00f9 se d\u00e9roulent les Nocturnes de la Villa Ephrussi ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">\u00c0 la Villa et Jardins Ephrussi de Rothschild, 1 avenue Ephrussi de Rothschild, 06230 Saint-Jean-Cap-Ferrat. Accessible en bus ligne 15 depuis Nice (arr\u00eat Passable\/Rothschild, devant la Villa) jusqu&rsquo;\u00e0 23h45, ou en navette gratuite depuis le boulevard g\u00e9n\u00e9ral de Gaulle.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quels sont les horaires des soir\u00e9es ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Ouverture \u00e0 20h, spectacle \u00e0 21h, fermeture \u00e0 minuit. Chaque lundi et mardi du 13 juillet au 25 ao\u00fbt 2026. Apr\u00e8s le spectacle, il est possible de d\u00e9ambuler librement dans les jardins illumin\u00e9s jusqu&rsquo;\u00e0 la fermeture.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Peut-on d\u00eener sur place ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Oui \u2014 la formule Nocturne + panier pique-nique est propos\u00e9e \u00e0 65 \u20ac (adulte), uniquement sur r\u00e9servation en ligne. \u00c0 d\u00e9guster dans les jardins illumin\u00e9s avant ou apr\u00e8s le spectacle.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Que se passe-t-il en cas d&rsquo;intemp\u00e9ries ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Si le spectacle est annul\u00e9 pour cause m\u00e9t\u00e9o, la visite de la Villa et des jardins reste maintenue. L&rsquo;\u00e9quipe propose de reporter la r\u00e9servation sur une autre date disponible dans la programmation.<\/p>\n<\/div>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"border-radius:10px;overflow:hidden;margin:20px 0;font-family:sans-serif\">\n  <tr>\n    <td width=\"170\" valign=\"middle\" style=\"background:#3b2210;padding:20px;text-align:center\">\n      <p style=\"font-size:20px;color:rgba(201,169,122,0.5);margin:0 0 6px\">\ud83c\udf39<\/p>\n      <p style=\"font-size:9px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#c9a97a;margin:0 0 6px;line-height:1.5\">G\u00eetes Domaine de la Chapelle<br>Roquefort-les-Pins<\/p>\n      <p style=\"font-size:14px;font-style:italic;color:#faeeda;margin:0;line-height:1.4\">Votre base \u00e0<br>30 min de la<br>Villa Ephrussi<\/p>\n    <\/td>\n    <td valign=\"middle\" style=\"background:#f5ede2;padding:18px 20px\">\n      <p style=\"font-size:13px;color:#555;margin:0 0 12px;line-height:1.7\">\u00c0 30 minutes de Saint-Jean-Cap-Ferrat \u2014 piscine chauff\u00e9e privative et jacuzzi en terrasse pour prolonger la magie de la soir\u00e9e aux chandelles.<\/p>\n      <p style=\"margin:0 0 12px\">\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udf39 30 min Villa Ephrussi<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udfca Piscine privative<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\u2668\ufe0f Jacuzzi privatif<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;display:inline-block\">\ud83c\udf3f Calme absolu<\/span>\n      <\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:8px 18px;font-weight:700;font-size:12px;text-decoration:none\">\ud83d\udcc5 Voir nos appartements<\/a>\n      <p style=\"font-size:10px;color:#888;margin:8px 0 0\">\ud83d\udd12 R\u00e9servation s\u00e9curis\u00e9e \u00b7 Confirmation imm\u00e9diate \u00b7 Annulation flexible<\/p>\n    <\/td>\n  <\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins Du 13 juillet au 25 ao\u00fbt 2026, la Villa Ephrussi de Rothschild \u00e0 Saint-Jean-Cap-Ferrat ouvre ses portes chaque lundi et mardi soir pour les Nocturnes de la Villa \u2014 l&rsquo;un des \u00e9v\u00e9nements les plus romanesque et les plus \u00e9l\u00e9gants de la C\u00f4te d&rsquo;Azur. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26572901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[128],"tags":[414,544,336,543,542],"dipi_cpt_category":[],"class_list":["post-26572899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-cote-azur","tag-evenement-cote-dazur-3","tag-nocturnes-de-la-villa","tag-saint-jean-cap-ferrat-2","tag-sortie-romantique","tag-villa-ephrussi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Nocturnes de la Villa Ephrussi 2026<\/title>\n<meta name=\"description\" content=\"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gitesdomainedelachapelle.com\/it\/nocturnes-villa-ephrussi-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Nocturnes de la Villa Ephrussi 2026\" \/>\n<meta property=\"og:description\" content=\"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/it\/nocturnes-villa-ephrussi-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00eetes Domaine de la Chapelle\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/patrice.campanella\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T10:38:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T17:39:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Patrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/\"},\"author\":{\"name\":\"Patrice\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\"},\"headline\":\"Les Nocturnes de la Villa Ephrussi 2026 : soir\u00e9es magiques \u00e0 Saint-Jean-Cap-Ferrat\",\"datePublished\":\"2026-06-01T10:38:18+00:00\",\"dateModified\":\"2026-06-15T17:39:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/\"},\"wordCount\":1055,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp\",\"keywords\":[\"\u00c9v\u00e9nement C\u00f4te d\u2019Azur\",\"Nocturnes de la Villa\",\"Saint-Jean-Cap-Ferrat\",\"Sortie romantique\",\"Villa Ephrussi\"],\"articleSection\":[\"Evenements sur la C\u00f4te d'Azur\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/\",\"name\":\"Les Nocturnes de la Villa Ephrussi 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp\",\"datePublished\":\"2026-06-01T10:38:18+00:00\",\"dateModified\":\"2026-06-15T17:39:33+00:00\",\"description\":\"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp\",\"width\":1536,\"height\":1024,\"caption\":\"Soir\u00e9es d'\u00e9t\u00e9 \u00e0 la Villa Ephrussi de Rothschild du 13 juillet au 25 ao\u00fbt 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/nocturnes-villa-ephrussi-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Nocturnes de la Villa Ephrussi 2026 : soir\u00e9es magiques \u00e0 Saint-Jean-Cap-Ferrat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"name\":\"Gites Domaine de la Chapelle\",\"description\":\"G\u00eetes de charme avec piscine chauff\u00e9e et jacuzzi privatif sur la C\u00f4te d\u2019Azur\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\",\"name\":\"Gites Domaine de la Chapelle\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"width\":1024,\"height\":1024,\"caption\":\"Gites Domaine de la Chapelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\",\"name\":\"Patrice\",\"pronouns\":\"nous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"caption\":\"Patrice\"},\"description\":\"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.\",\"sameAs\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\",\"https:\\\/\\\/www.facebook.com\\\/patrice.campanella\\\/\",\"https:\\\/\\\/www.instagram.com\\\/piscine_jacuzzi_cotedazur\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/gitesdomainedelachapelle\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gitesdomainedelachapelle\"],\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/it\\\/author\\\/patrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Nocturnes de la Villa Ephrussi 2026","description":"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gitesdomainedelachapelle.com\/it\/nocturnes-villa-ephrussi-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Les Nocturnes de la Villa Ephrussi 2026","og_description":"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.","og_url":"https:\/\/www.gitesdomainedelachapelle.com\/it\/nocturnes-villa-ephrussi-2026\/","og_site_name":"G\u00eetes Domaine de la Chapelle","article_author":"https:\/\/www.facebook.com\/patrice.campanella\/","article_published_time":"2026-06-01T10:38:18+00:00","article_modified_time":"2026-06-15T17:39:33+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp","type":"image\/webp"}],"author":"Patrice","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrice","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#article","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/"},"author":{"name":"Patrice","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004"},"headline":"Les Nocturnes de la Villa Ephrussi 2026 : soir\u00e9es magiques \u00e0 Saint-Jean-Cap-Ferrat","datePublished":"2026-06-01T10:38:18+00:00","dateModified":"2026-06-15T17:39:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/"},"wordCount":1055,"commentCount":0,"publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp","keywords":["\u00c9v\u00e9nement C\u00f4te d\u2019Azur","Nocturnes de la Villa","Saint-Jean-Cap-Ferrat","Sortie romantique","Villa Ephrussi"],"articleSection":["Evenements sur la C\u00f4te d'Azur"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/","name":"Les Nocturnes de la Villa Ephrussi 2026","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp","datePublished":"2026-06-01T10:38:18+00:00","dateModified":"2026-06-15T17:39:33+00:00","description":"Les Nocturnes de la Villa Ephrussi 2026 \u00e0 Saint-Jean-Cap-Ferrat : concerts, spectacles et jardins illumin\u00e9s sur la C\u00f4te d\u2019Azur.","breadcrumb":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#primaryimage","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/soirees-ete-villa-ephrussi-saint-jean-cap-ferrat-2026.webp","width":1536,"height":1024,"caption":"Soir\u00e9es d'\u00e9t\u00e9 \u00e0 la Villa Ephrussi de Rothschild du 13 juillet au 25 ao\u00fbt 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gitesdomainedelachapelle.com\/nocturnes-villa-ephrussi-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gitesdomainedelachapelle.com\/"},{"@type":"ListItem","position":2,"name":"Les Nocturnes de la Villa Ephrussi 2026 : soir\u00e9es magiques \u00e0 Saint-Jean-Cap-Ferrat"}]},{"@type":"WebSite","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website","url":"https:\/\/www.gitesdomainedelachapelle.com\/","name":"Gites Domaine de la Chapelle","description":"G\u00eetes di charme con piscina riscaldata e jacuzzi privata sulla Costa Azzurra","publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gitesdomainedelachapelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization","name":"Gites Domaine de la Chapelle","url":"https:\/\/www.gitesdomainedelachapelle.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","width":1024,"height":1024,"caption":"Gites Domaine de la Chapelle"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004","name":"Patrice","pronouns":"nous","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","caption":"Patrice"},"description":"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.","sameAs":["https:\/\/www.gitesdomainedelachapelle.com","https:\/\/www.facebook.com\/patrice.campanella\/","https:\/\/www.instagram.com\/piscine_jacuzzi_cotedazur\/","https:\/\/www.linkedin.com\/in\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\/","https:\/\/fr.pinterest.com\/gitesdomainedelachapelle\/","https:\/\/www.youtube.com\/@gitesdomainedelachapelle"],"url":"https:\/\/www.gitesdomainedelachapelle.com\/it\/author\/patrice\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/posts\/26572899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/comments?post=26572899"}],"version-history":[{"count":3,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/posts\/26572899\/revisions"}],"predecessor-version":[{"id":26573417,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/posts\/26572899\/revisions\/26573417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/media\/26572901"}],"wp:attachment":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/media?parent=26572899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/categories?post=26572899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/tags?post=26572899"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/it\/wp-json\/wp\/v2\/dipi_cpt_category?post=26572899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}