{"id":26572336,"date":"2026-05-07T06:15:57","date_gmt":"2026-05-07T05:15:57","guid":{"rendered":"https:\/\/www.gitesdomainedelachapelle.com\/?p=26572336"},"modified":"2026-06-21T06:54:48","modified_gmt":"2026-06-21T05:54:48","slug":"les-voiles-antibes-2026-cote-azur","status":"publish","type":"post","link":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/les-voiles-antibes-2026-cote-azur\/","title":{"rendered":"Les Voiles d\u2019Antibes 2026 : un rendez-vous nautique incontournable sur la C\u00f4te d\u2019Azur"},"content":{"rendered":"<p style=\"font-family:sans-serif;font-size:13px;color:#888;margin-bottom:8px\">Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins<\/p>\n\n<p style=\"font-size:15px;color:#444;border-left:3px solid #c9a97a;padding:12px 18px;background:#f5ede2;border-radius:0 8px 8px 0;margin-bottom:14px;line-height:1.9\">Du <strong>27 au 31 mai 2026<\/strong>, le Port Vauban d&rsquo;Antibes accueille les <strong>Voiles d&rsquo;Antibes<\/strong> \u2014 l&rsquo;un des rassemblements de yachts classiques les plus prestigieux de la M\u00e9diterran\u00e9e. Voiliers historiques venus du monde entier, r\u00e9gates en mer, promenades sur les quais au c\u0153ur de l&rsquo;un des plus beaux ports de la C\u00f4te d&rsquo;Azur \u2014 cinq jours d&rsquo;\u00e9l\u00e9gance maritime \u00e0 12 km des G\u00eetes Domaine de la Chapelle.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Les Voiles d&rsquo;Antibes \u2014 Un patrimoine maritime exceptionnel<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Cr\u00e9\u00e9es dans les ann\u00e9es 1990, les Voiles d&rsquo;Antibes ouvrent chaque printemps le circuit m\u00e9diterran\u00e9en des r\u00e9gates de yachts classiques \u2014 une saison qui encha\u00eene ensuite les <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/voiles-saint-tropez-2026\/\" style=\"color:#a07850\">Voiles de Saint-Tropez<\/a>, Portofino et les <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/voiles-monaco-2026\/\" style=\"color:#a07850\">Voiles de Monaco<\/a>. Le Port Vauban, l&rsquo;un des plus grands ports de plaisance de M\u00e9diterran\u00e9e, devient pendant cinq jours le th\u00e9\u00e2tre d&rsquo;un spectacle maritime exceptionnel \u2014 des voiliers historiques du XIXe et XXe si\u00e8cles, des ketchs en bois laqu\u00e9, des go\u00e9lettes et des sloops venus de toute l&rsquo;Europe. Une concentration de patrimoine naval vivant rarement \u00e9gal\u00e9e en M\u00e9diterran\u00e9e. Pour le programme complet des r\u00e9gates et les informations pratiques, <a href=\"https:\/\/www.antibesjuanlespins.com\/\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">l&rsquo;Office de Tourisme officiel d&rsquo;Antibes Juan-les-Pins<\/a> centralise les informations de l&rsquo;\u00e9v\u00e9nement.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Ce qu&rsquo;on vit aux Voiles d&rsquo;Antibes<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">L&rsquo;exp\u00e9rience commence sur les quais du Port Vauban \u2014 les yachts classiques sont accessibles \u00e0 la vue de pr\u00e8s pendant les p\u00e9riodes d&rsquo;exposition, leurs propri\u00e9taires et \u00e9quipages pr\u00e9sents pour r\u00e9pondre aux questions. Les r\u00e9gates se d\u00e9roulent en mer, dans la baie d&rsquo;Antibes \u2014 observables depuis le Cap d&rsquo;Antibes ou depuis les remparts Vauban pour une vue plongeante sur les voiliers en comp\u00e9tition. Un village exposants s&rsquo;installe sur le port \u2014 artisanat nautique, accessoires de navigation, gastronomie maritime. L&rsquo;ambiance y est \u00e9l\u00e9gante et d\u00e9tendue, typiquement m\u00e9diterran\u00e9enne \u2014 loin du spectacle bruyant d&rsquo;autres \u00e9v\u00e9nements sportifs. Pour explorer les alentours entre deux r\u00e9gates, les <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/plages-antibes-juan-les-pins\/\" style=\"color:#a07850\">plages de Juan-les-Pins<\/a> sont \u00e0 5 minutes du port.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Antibes pendant les Voiles \u2014 La ville sous son plus beau visage<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Les Voiles d&rsquo;Antibes donnent \u00e0 la ville une atmosph\u00e8re unique \u2014 le vieux port anim\u00e9, les restaurants des quais pris d&rsquo;assaut par les \u00e9quipages internationaux, le Vieux-Antibes et son march\u00e9 proven\u00e7al en plein printemps. C&rsquo;est l&rsquo;occasion id\u00e9ale de d\u00e9couvrir Antibes dans une ambiance particuli\u00e8re \u2014 entre l&rsquo;\u00e9l\u00e9gance des yachts classiques et l&rsquo;authenticit\u00e9 des remparts Vauban. Notre guide du <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/visiter-cap-antibes\/\" style=\"color:#a07850\">sentier du Littoral au Cap d&rsquo;Antibes<\/a> propose une balade \u00e0 pied pour observer les r\u00e9gates depuis les falaises \u2014 un point de vue in\u00e9dit sur l&rsquo;\u00e9v\u00e9nement.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">S\u00e9journer \u00e0 l&rsquo;arri\u00e8re-pays pour les Voiles d&rsquo;Antibes<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Antibes en p\u00e9riode d&rsquo;\u00e9v\u00e9nement \u2014 les h\u00e9bergements sur le port et en centre-ville sont rapidement satur\u00e9s et les tarifs augmentent. Depuis les <strong>G\u00eetes Domaine de la Chapelle<\/strong> \u00e0 Roquefort-les-Pins, Antibes est \u00e0 12 km \u2014 15 minutes en voiture, ou 20 minutes depuis la gare d&rsquo;Antibes en partant de Cagnes-sur-Mer. Appartements privatifs avec piscine chauff\u00e9e couverte et spa ou jacuzzi en terrasse exclusive dans la garrigue proven\u00e7ale. Cinq jours aux Voiles d&rsquo;Antibes le jour, spa privatif et silence de la garrigue le soir \u2014 l&rsquo;\u00e9quilibre parfait pour un s\u00e9jour de qualit\u00e9.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Questions fr\u00e9quentes<\/h2>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quand ont lieu les Voiles d&rsquo;Antibes 2026 ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Du <strong>27 au 31 mai 2026<\/strong> au Port Vauban d&rsquo;Antibes. Les r\u00e9gates se d\u00e9roulent en mer pendant la journ\u00e9e, les expositions et animations sur les quais en continu.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">L&rsquo;acc\u00e8s aux Voiles d&rsquo;Antibes est-il gratuit ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">L&rsquo;acc\u00e8s aux quais et \u00e0 l&rsquo;exposition de voiliers est en grande partie gratuit pour les visiteurs. Certains espaces VIP et \u00e9v\u00e9nements sp\u00e9cifiques peuvent n\u00e9cessiter un billet \u2014 v\u00e9rifier le programme officiel pour les d\u00e9tails de chaque journ\u00e9e.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Peut-on observer les r\u00e9gates depuis le rivage ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Oui \u2014 depuis le sentier du Littoral au Cap d&rsquo;Antibes, les remparts Vauban du Vieux-Antibes et certaines plages de la baie, les voiliers en r\u00e9gate sont visibles \u00e0 l&rsquo;\u0153il nu. Pour une vue plus rapproch\u00e9e, des sorties en bateau sont parfois propos\u00e9es pendant l&rsquo;\u00e9v\u00e9nement.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Comment se rendre au Port Vauban depuis l&rsquo;arri\u00e8re-pays ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Depuis Roquefort-les-Pins \u2014 15 minutes en voiture jusqu&rsquo;au parking du Port Vauban ou du centre d&rsquo;Antibes. En train depuis Cagnes-sur-Mer (12 km) \u2014 la gare d&rsquo;Antibes est \u00e0 10 minutes \u00e0 pied du Port Vauban. Recommand\u00e9 en soir\u00e9e pour \u00e9viter le stationnement.<\/p>\n<\/div>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"border-radius:10px;overflow:hidden;margin:20px 0;font-family:sans-serif\">\n  <tr>\n    <td width=\"170\" valign=\"middle\" style=\"background:#3b2210;padding:20px;text-align:center\">\n      <p style=\"font-size:20px;color:rgba(201,169,122,0.5);margin:0 0 6px\">\u26f5<\/p>\n      <p style=\"font-size:9px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#c9a97a;margin:0 0 6px;line-height:1.5\">G\u00eetes Domaine de la Chapelle<br>Roquefort-les-Pins<\/p>\n      <p style=\"font-size:14px;font-style:italic;color:#faeeda;margin:0;line-height:1.4\">Base id\u00e9ale pour<br>les Voiles d&rsquo;Antibes<br>27-31 mai 2026<\/p>\n    <\/td>\n    <td valign=\"middle\" style=\"background:#f5ede2;padding:18px 20px\">\n      <p style=\"font-size:13px;color:#555;margin:0 0 12px;line-height:1.7\">Trois appartements privatifs avec piscine chauff\u00e9e et spa ou jacuzzi \u2014 \u00e0 12 km d&rsquo;Antibes, base id\u00e9ale pour 5 jours aux Voiles.<\/p>\n      <p style=\"margin:0 0 12px\">\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\u26f5 Antibes 12 km<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\u2668\ufe0f Spa privatif<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udfca Piscine chauff\u00e9e<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;display:inline-block\">\ud83c\udf3f Calme<\/span>\n      <\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/location-vacances-cote-azur\/\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:8px 18px;font-weight:700;font-size:12px;text-decoration:none\">\ud83d\udcc5 Voir nos disponibilit\u00e9s<\/a>\n      <p style=\"font-size:10px;color:#888;margin:8px 0 0\">\ud83d\udd12 R\u00e9servation s\u00e9curis\u00e9e \u00b7 Confirmation imm\u00e9diate \u00b7 Annulation flexible<\/p>\n    <\/td>\n  <\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins Du 27 au 31 mai 2026, le Port Vauban d&rsquo;Antibes accueille les Voiles d&rsquo;Antibes \u2014 l&rsquo;un des rassemblements de yachts classiques les plus prestigieux de la M\u00e9diterran\u00e9e. Voiliers historiques venus du monde entier, r\u00e9gates en mer, promenades sur les quais au c\u0153ur de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26572337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[128],"tags":[253,251,250,252],"dipi_cpt_category":[],"class_list":["post-26572336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-cote-azur","tag-antibes-cote-d-azur","tag-les-voiles-d-antibes","tag-les-voiles-d-antibes-2026","tag-regates-mediterranee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Voiles d Antibes 2026 sur la Cote d Azur<\/title>\n<meta name=\"description\" content=\"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gitesdomainedelachapelle.com\/pt\/les-voiles-antibes-2026-cote-azur\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Voiles d Antibes 2026 sur la Cote d Azur\" \/>\n<meta property=\"og:description\" content=\"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/pt\/les-voiles-antibes-2026-cote-azur\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00eetes Domaine de la Chapelle\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/patrice.campanella\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T05:15:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-21T05:54:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Patrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/\"},\"author\":{\"name\":\"Patrice\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\"},\"headline\":\"Les Voiles d\u2019Antibes 2026 : un rendez-vous nautique incontournable sur la C\u00f4te d\u2019Azur\",\"datePublished\":\"2026-05-07T05:15:57+00:00\",\"dateModified\":\"2026-06-21T05:54:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/\"},\"wordCount\":841,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/les-voiles-antibes-regates-cote-azur-2026.webp\",\"keywords\":[\"antibes cote d azur\",\"les voiles d antibes\",\"les voiles d antibes 2026\",\"regates mediterranee\"],\"articleSection\":[\"Evenements sur la C\u00f4te d'Azur\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/\",\"name\":\"Les Voiles d Antibes 2026 sur la Cote d Azur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/les-voiles-antibes-regates-cote-azur-2026.webp\",\"datePublished\":\"2026-05-07T05:15:57+00:00\",\"dateModified\":\"2026-06-21T05:54:48+00:00\",\"description\":\"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/les-voiles-antibes-regates-cote-azur-2026.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/les-voiles-antibes-regates-cote-azur-2026.webp\",\"width\":1200,\"height\":800,\"caption\":\"Voiliers classiques participant aux Voiles d Antibes sur la Cote d Azur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/les-voiles-antibes-2026-cote-azur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Voiles d\u2019Antibes 2026 : un rendez-vous nautique incontournable sur la C\u00f4te d\u2019Azur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"name\":\"Gites Domaine de la Chapelle\",\"description\":\"G\u00eetes de charme avec piscine chauff\u00e9e et jacuzzi privatif sur la C\u00f4te d\u2019Azur\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\",\"name\":\"Gites Domaine de la Chapelle\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"width\":1024,\"height\":1024,\"caption\":\"Gites Domaine de la Chapelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\",\"name\":\"Patrice\",\"pronouns\":\"nous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"caption\":\"Patrice\"},\"description\":\"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.\",\"sameAs\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\",\"https:\\\/\\\/www.facebook.com\\\/patrice.campanella\\\/\",\"https:\\\/\\\/www.instagram.com\\\/piscine_jacuzzi_cotedazur\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/gitesdomainedelachapelle\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gitesdomainedelachapelle\"],\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/pt\\\/author\\\/patrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Voiles d Antibes 2026 sur la Cote d Azur","description":"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/les-voiles-antibes-2026-cote-azur\/","og_locale":"pt_PT","og_type":"article","og_title":"Les Voiles d Antibes 2026 sur la Cote d Azur","og_description":"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.","og_url":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/les-voiles-antibes-2026-cote-azur\/","og_site_name":"G\u00eetes Domaine de la Chapelle","article_author":"https:\/\/www.facebook.com\/patrice.campanella\/","article_published_time":"2026-05-07T05:15:57+00:00","article_modified_time":"2026-06-21T05:54:48+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp","type":"image\/webp"}],"author":"Patrice","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Patrice","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#article","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/"},"author":{"name":"Patrice","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004"},"headline":"Les Voiles d\u2019Antibes 2026 : un rendez-vous nautique incontournable sur la C\u00f4te d\u2019Azur","datePublished":"2026-05-07T05:15:57+00:00","dateModified":"2026-06-21T05:54:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/"},"wordCount":841,"commentCount":0,"publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp","keywords":["antibes cote d azur","les voiles d antibes","les voiles d antibes 2026","regates mediterranee"],"articleSection":["Evenements sur la C\u00f4te d'Azur"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/","name":"Les Voiles d Antibes 2026 sur la Cote d Azur","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#primaryimage"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp","datePublished":"2026-05-07T05:15:57+00:00","dateModified":"2026-06-21T05:54:48+00:00","description":"Les Voiles d Antibes 2026 : regates, voiliers historiques et ambiance maritime sur la Cote d Azur du 27 au 31 mai.","breadcrumb":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#primaryimage","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/05\/les-voiles-antibes-regates-cote-azur-2026.webp","width":1200,"height":800,"caption":"Voiliers classiques participant aux Voiles d Antibes sur la Cote d Azur"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gitesdomainedelachapelle.com\/les-voiles-antibes-2026-cote-azur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gitesdomainedelachapelle.com\/"},{"@type":"ListItem","position":2,"name":"Les Voiles d\u2019Antibes 2026 : un rendez-vous nautique incontournable sur la C\u00f4te d\u2019Azur"}]},{"@type":"WebSite","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website","url":"https:\/\/www.gitesdomainedelachapelle.com\/","name":"Gites Domaine de la Chapelle","description":"Alojamentos de charme com piscina aquecida e jacuzzi privado na C\u00f4te d\u2019Azur","publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gitesdomainedelachapelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization","name":"Gites Domaine de la Chapelle","url":"https:\/\/www.gitesdomainedelachapelle.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","width":1024,"height":1024,"caption":"Gites Domaine de la Chapelle"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004","name":"Patrice","pronouns":"nous","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","caption":"Patrice"},"description":"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.","sameAs":["https:\/\/www.gitesdomainedelachapelle.com","https:\/\/www.facebook.com\/patrice.campanella\/","https:\/\/www.instagram.com\/piscine_jacuzzi_cotedazur\/","https:\/\/www.linkedin.com\/in\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\/","https:\/\/fr.pinterest.com\/gitesdomainedelachapelle\/","https:\/\/www.youtube.com\/@gitesdomainedelachapelle"],"url":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/author\/patrice\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/comments?post=26572336"}],"version-history":[{"count":3,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572336\/revisions"}],"predecessor-version":[{"id":26573685,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572336\/revisions\/26573685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/media\/26572337"}],"wp:attachment":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/media?parent=26572336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/categories?post=26572336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/tags?post=26572336"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/dipi_cpt_category?post=26572336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}