{"id":26572894,"date":"2026-06-01T07:15:51","date_gmt":"2026-06-01T06:15:51","guid":{"rendered":"https:\/\/www.gitesdomainedelachapelle.com\/?p=26572894"},"modified":"2026-06-15T13:25:16","modified_gmt":"2026-06-15T12:25:16","slug":"ligue-diamant-monaco-2026","status":"publish","type":"post","link":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/ligue-diamant-monaco-2026\/","title":{"rendered":"Ligue de Diamant Monaco 2026 : les stars mondiales de l\u2019athl\u00e9tisme au Stade Louis-II"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p style=\"font-family:sans-serif;font-size:13px;color:#888;margin-bottom:8px\">Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins<\/p>\n\n<p style=\"font-size:15px;color:#444;border-left:3px solid #c9a97a;padding:12px 18px;background:#f5ede2;border-radius:0 8px 8px 0;margin-bottom:14px;line-height:1.9\">Levar <strong>vendredi 10 juillet 2026 \u00e0 19h<\/strong>, le Stade Louis-II de <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/monaco-cote-azur\/\" style=\"color:#a07850\">Monaco<\/a> accueille la <strong>40e \u00e9dition du Meeting Herculis EBS<\/strong> \u2014 10e \u00e9tape de la <strong>Wanda Diamond League<\/strong>, le circuit d&rsquo;athl\u00e9tisme le plus prestigieux au monde. Class\u00e9 <strong>meilleur meeting du monde \u00e0 sept reprises<\/strong> (2011, 2014, 2015, 2018, 2020 et deux autres \u00e9ditions), cet \u00e9v\u00e9nement sous la pr\u00e9sidence de <strong>S.A.S. le Prince Albert II<\/strong> r\u00e9unit champions olympiques, recordmen du monde et prodiges sur la piste l\u00e9gendaire de la Principaut\u00e9. \u00c0 <strong>40 minutes<\/strong> desligar <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"color:#a07850\">G\u00eetes Domaine de la Chapelle<\/a>.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Un meeting n\u00e9 en 1987 \u2014 40 ans d&rsquo;histoire et de records du monde<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Cr\u00e9\u00e9 en <strong>1987<\/strong>, le Meeting Herculis EBS s&rsquo;est impos\u00e9 au fil des d\u00e9cennies comme l&rsquo;une des \u00e9tapes les plus attendues de la saison internationale d&rsquo;athl\u00e9tisme. Depuis son int\u00e9gration \u00e0 la Diamond League en <strong>2010<\/strong>, il a d\u00e9croch\u00e9 \u00e0 cinq reprises le titre de <strong>meilleur meeting au monde<\/strong>. La piste du Stade Louis-II a \u00e9t\u00e9 le th\u00e9\u00e2tre de performances historiques m\u00e9morables \u2014 le record du monde du Mile f\u00e9minin de <strong>Faith Kipyegon en 2023<\/strong> (4&rsquo;07&Prime;64), le record du monde du 2000 m de <strong>Jessica Hull en 2024<\/strong> (5&rsquo;19&Prime;70), ou le 400 m de <strong>Quincy Hall<\/strong> en 43&Prime;80 la m\u00eame ann\u00e9e. L&rsquo;\u00e9dition 2026 s&rsquo;annonce \u00e0 la hauteur de cette r\u00e9putation \u2014 <strong>Mondo Duplantis<\/strong> \u00e0 la perche et <strong>Faith Kipyegon<\/strong> au 3000 m figurent parmi les attractions majeures confirm\u00e9es.<\/p>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Les disciplines au programme 2026<\/h2>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 10px\">Meeting Herculis EBS 2026 \u2014 Disciplines confirm\u00e9es<\/p>\n      <table width=\"100%\" cellpadding=\"5\" cellspacing=\"0\" border=\"0\" style=\"font-size:12px;color:#555\">\n        <tr style=\"background:#3b2210;color:#faeeda;font-weight:700\">\n          <td style=\"padding:5px 10px;border-radius:4px 0 0 0;width:50%\">\ud83c\udfc3 Hommes<\/td>\n          <td style=\"padding:5px 10px;border-radius:0 4px 0 0\">\ud83c\udfc3 Femmes<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px\">100 m \u00b7 400 m \u00b7 800 m<\/td>\n          <td style=\"padding:6px 10px\">200 m \u00b7 400 m<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px\">3 000 m \/ 5 000 m<\/td>\n          <td style=\"padding:6px 10px\">3 000 m \/ 5 000 m \u00b7 100 m haies<\/td>\n        <\/tr>\n        <tr style=\"background:#fff\">\n          <td style=\"padding:6px 10px\">3 000 m steeple<\/td>\n          <td style=\"padding:6px 10px\">Saut \u00e0 la perche \u00b7 Triple saut<\/td>\n        <\/tr>\n        <tr style=\"background:#fafafa\">\n          <td style=\"padding:6px 10px\">Saut en hauteur \u00b7 Saut en longueur<\/td>\n          <td style=\"padding:6px 10px\">Lancer du javelot<\/td>\n        <\/tr>\n      <\/table>\n      <p style=\"font-size:11px;color:#a07850;margin:10px 0 0\">\u2b50 Attractions confirm\u00e9es : <strong>Mondo Duplantis<\/strong> (perche \u00b7 recordman du monde) \u00b7 <strong>Faith Kipyegon<\/strong> (3000 m \u00b7 recordwoman du Mile \u00e0 Monaco en 2023) \u00b7 <strong>Jimmy Gressier<\/strong> (5000 m) \u00b7 et 12 nouveaux champions internationaux annonc\u00e9s<\/p>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Une soir\u00e9e unique dans le Stade Louis-II<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">Levar <strong>Stade Louis-II<\/strong> (7, avenue des Castelans, Monaco) est l&rsquo;un des stades les plus singuliers au monde \u2014 construit en partie au-dessus de la mer, dans la principaut\u00e9 la plus dens\u00e9ment peupl\u00e9e de la plan\u00e8te. Sa configuration intimiste permet une <strong>proximit\u00e9 exceptionnelle avec les athl\u00e8tes<\/strong> \u2014 les spectateurs sont \u00e0 quelques m\u00e8tres de la piste et peuvent entendre les coulisses de la comp\u00e9tition. <strong>TVMonaco<\/strong> est devenu en 2026 partenaire majeur et diffuseur h\u00f4te du meeting \u2014 une premi\u00e8re historique qui renforce le rayonnement international de l&rsquo;\u00e9v\u00e9nement. Pour pr\u00e9parer votre journ\u00e9e avant le meeting, notre guide <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/monaco-cote-azur\/\" style=\"color:#a07850\">Monaco sur la C\u00f4te d&rsquo;Azur<\/a> vous donnera toutes les id\u00e9es de visite.<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#f5ede2;border-left:3px solid #c9a97a;border-radius:0 8px 8px 0;margin:20px 0\">\n  <tr>\n    <td style=\"padding:14px 18px\">\n      <p style=\"font-family:sans-serif;font-size:11px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#a07850;margin:0 0 6px\">Infos pratiques \u2014 Meeting Herculis EBS 2026<\/p>\n      <p style=\"font-size:13px;color:#555;margin:0;line-height:1.9\">\n        <strong>Date :<\/strong> Vendredi 10 juillet 2026 \u00b7 D\u00e9but \u00e0 <strong>19h<\/strong> \u00b7 40e \u00e9dition<br>\n        <strong>Lieu :<\/strong> Stade Louis-II \u00b7 7 avenue des Castelans \u00b7 Monaco<br>\n        <strong>Tarifs :<\/strong> \u00c0 partir de <strong>15 \u20ac<\/strong> \u00b7 Tarif r\u00e9duit sur justificatif \u00b7 Groupes (10+ personnes) tarif r\u00e9duit sur demande<br>\n        <strong>Billetterie :<\/strong> <a href=\"https:\/\/monaco-diamond-league.com\/fr\/\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">monaco-diamond-league.com<\/a> \u00b7 Guichets Stade Louis-II \u00e0 partir du lundi 29 juin (10h-12h30 et 13h30-18h30)<br>\n        <strong>Acc\u00e8s train :<\/strong> Gare de Monaco-Monte-Carlo (ligne Nice-Vintimille) \u00b7 10 min \u00e0 pied<br>\n        <strong>Acc\u00e8s voiture :<\/strong> A8 sortie Monaco \u00b7 parking dans les environs\n      <\/p>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Votre base id\u00e9ale \u00e0 40 minutes de Monaco<\/h2>\n\n<p style=\"line-height:1.9;margin-bottom:14px\">\u00c0 <strong>40 minutes de Monaco<\/strong>, les <strong>G\u00eetes Domaine de la Chapelle<\/strong> \u00e0 Roquefort-les-Pins sont votre base id\u00e9ale pour le Meeting Herculis. Monaco est facilement accessible en train depuis Nice. Retrouvez notre <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/appartement-vacances-couple-cote-azur\/\" style=\"color:#a07850\">appartement vacances en couple sur la C\u00f4te d&rsquo;Azur<\/a>, avec piscine chauff\u00e9e et jacuzzi privatifs \u2014 la d\u00e9tente garantie apr\u00e8s une grande soir\u00e9e d&rsquo;athl\u00e9tisme.<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"margin:20px 0;border-collapse:separate;border-spacing:10px\">\n  <tr valign=\"top\">\n    <td width=\"33%\" style=\"background:#ffffff;border:2px solid #c9a97a;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#3b2210;color:#c9a97a;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2605 Le plus luxueux<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf77 L&rsquo;Asti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Grand espace, piscine chauff\u00e9e + jacuzzi haut de gamme<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi haut de gamme en terrasse<br>\u2714 Lit Queen size, clim, WiFi, Netflix<br>\u2714 Grande terrasse, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 Voir L&rsquo;Asti<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\u2668\ufe0f Vrai spa privatif<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83c\udf0a Le Bari<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Spa privatif 3 places sous les \u00e9toiles<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Spa privatif 3 places en terrasse<br>\u2714 Acc\u00e8s piscine chauff\u00e9e couverte<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Nespresso, cuisine \u00e9quip\u00e9e<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/en\/le-bari\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Bari<\/a>\n    <\/td>\n    <td width=\"33%\" style=\"background:#ffffff;border:1px solid #e8d5c4;border-radius:10px;padding:16px\">\n      <p style=\"display:inline-block;font-size:10px;font-weight:700;background:#faeeda;color:#a07850;border-radius:20px;padding:2px 10px;margin:0 0 6px\">\ud83c\udfca Piscine + jacuzzi<\/p>\n      <p style=\"font-size:14px;font-weight:700;color:#3b2210;margin:0 0 4px\">\ud83e\uded2 Le Chianti<\/p>\n      <p style=\"font-size:11px;font-style:italic;color:#a07850;margin:0 0 8px\">Design et contemporain, piscine + jacuzzi<\/p>\n      <p style=\"font-size:11px;color:#555;margin:0 0 8px;line-height:1.7\">\u2714 Piscine chauff\u00e9e couverte privative<br>\u2714 Jacuzzi privatif en terrasse<br>\u2714 Lit Queen size, clim, WiFi<br>\u2714 Design contemporain, parking priv\u00e9<\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"font-size:11px;font-weight:700;color:#a07850;text-decoration:none\">\u2192 D\u00e9couvrir Le Chianti<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<p style=\"font-family:sans-serif;font-size:13px;background:#f5ede2;border-radius:8px;padding:12px 16px;margin:20px 0\">\n  \ud83c\udfa5 <strong>D\u00e9couvrez les G\u00eetes Domaine de la Chapelle en vid\u00e9o<\/strong> &nbsp;\u00b7&nbsp;\n  <a href=\"https:\/\/www.youtube.com\/watch?v=1GOP2RP_sw8\" target=\"_blank\" rel=\"noopener\" style=\"color:#a07850\">\u25b6 Voir la vid\u00e9o<\/a>\n<\/p>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"background:#3b2210;border-radius:10px;margin:20px 0\">\n  <tr>\n    <td style=\"padding:20px 24px;text-align:center\">\n      <p style=\"font-size:19px;font-style:italic;color:#faeeda;margin:0 0 8px\">Herculis \u00e0 Monaco \u2014 piscine et jacuzzi privatifs au retour.<\/p>\n      <p style=\"font-size:13px;color:#c9a97a;margin:0 0 16px\">\u00c0 40 min de Monaco \u00b7 Disponibilit\u00e9s en temps r\u00e9el.<\/p>\n      <a href=\"https:\/\/via.eviivo.com\/GtsDmndlChpll06330\" target=\"_blank\" rel=\"noopener\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:10px 24px;font-weight:700;font-family:sans-serif;font-size:13px;text-decoration:none\">\u2726 V\u00e9rifier les disponibilit\u00e9s et r\u00e9server<\/a>\n    <\/td>\n  <\/tr>\n<\/table>\n\n<h2 style=\"font-size:21px;color:#5c3a1e;border-left:4px solid #c9a97a;padding-left:12px;margin-top:32px;margin-bottom:12px\">Questions fr\u00e9quentes<\/h2>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quelle est la 40e \u00e9dition du Meeting Herculis ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Le Meeting Herculis EBS a \u00e9t\u00e9 cr\u00e9\u00e9 en 1987. L&rsquo;\u00e9dition 2026 est donc la 40e. Class\u00e9 4e meeting au monde en 2025, il a remport\u00e9 le titre de meilleur meeting au monde \u00e0 sept reprises dans son histoire (2011, 2014, 2015, 2018, 2020 notamment).<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quels athl\u00e8tes sont confirm\u00e9s pour 2026 ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Mondo Duplantis (perche, recordman du monde \u00e0 6,26 m) et Faith Kipyegon (3000 m, elle a \u00e9tabli le record du monde du Mile \u00e0 Monaco en 2023) figurent parmi les t\u00eates d&rsquo;affiche confirm\u00e9es. Jimmy Gressier est annonc\u00e9 au 5000 m. Douze autres champions internationaux ont \u00e9t\u00e9 confirm\u00e9s \u00e0 un mois du meeting.<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">Quel est le tarif des billets ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">\u00c0 partir de 15 \u20ac. Tarif r\u00e9duit sur justificatif aux guichets. Groupes de 10 personnes et plus : tarif r\u00e9duit sur demande. Billetterie en ligne sur monaco-diamond-league.com ou aux guichets du Stade Louis-II \u00e0 partir du 29 juin (10h-12h30 et 13h30-18h30).<\/p>\n<\/div>\n\n<div style=\"margin-bottom:14px\">\n  <p style=\"font-size:15px;font-weight:700;color:#3b2210;margin:0 0 4px\">L&rsquo;\u00e9v\u00e9nement est-il adapt\u00e9 aux familles ?<\/p>\n  <p style=\"line-height:1.9;color:#444;margin:0\">Oui \u2014 le Meeting Herculis est accessible \u00e0 tous les publics. La proximit\u00e9 avec les athl\u00e8tes dans le Stade Louis-II offre une exp\u00e9rience unique, m\u00eame pour les non-initi\u00e9s. Une soir\u00e9e id\u00e9ale pour faire d\u00e9couvrir l&rsquo;athl\u00e9tisme de haut niveau \u00e0 des enfants.<\/p>\n<\/div>\n\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" border=\"0\" style=\"border-radius:10px;overflow:hidden;margin:20px 0;font-family:sans-serif\">\n  <tr>\n    <td width=\"170\" valign=\"middle\" style=\"background:#3b2210;padding:20px;text-align:center\">\n      <p style=\"font-size:20px;color:rgba(201,169,122,0.5);margin:0 0 6px\">\ud83c\udfc3<\/p>\n      <p style=\"font-size:9px;font-weight:700;letter-spacing:.1em;text-transform:uppercase;color:#c9a97a;margin:0 0 6px;line-height:1.5\">G\u00eetes Domaine de la Chapelle<br>Roquefort-les-Pins<\/p>\n      <p style=\"font-size:14px;font-style:italic;color:#faeeda;margin:0;line-height:1.4\">Votre base \u00e0<br>40 min du<br>Meeting Herculis<\/p>\n    <\/td>\n    <td valign=\"middle\" style=\"background:#f5ede2;padding:18px 20px\">\n      <p style=\"font-size:13px;color:#555;margin:0 0 12px;line-height:1.7\">\u00c0 40 minutes de Monaco et du Stade Louis-II \u2014 piscine chauff\u00e9e privative et jacuzzi en terrasse pour rentrer se ressourcer apr\u00e8s une grande soir\u00e9e d&rsquo;athl\u00e9tisme mondial.<\/p>\n      <p style=\"margin:0 0 12px\">\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udfc3 40 min de Monaco<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\ud83c\udfca Piscine privative<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;margin-right:5px;display:inline-block\">\u2668\ufe0f Jacuzzi privatif<\/span>\n        <span style=\"font-size:11px;background:#ffffff;border:1px solid #e8d5c4;border-radius:20px;padding:3px 10px;display:inline-block\">\ud83c\udf3f Calme absolu<\/span>\n      <\/p>\n      <a href=\"https:\/\/www.gitesdomainedelachapelle.com\/nos-appartements\/\" style=\"display:inline-block;background:#c9a97a;color:#3b2210;border-radius:6px;padding:8px 18px;font-weight:700;font-size:12px;text-decoration:none\">\ud83d\udcc5 Voir nos appartements<\/a>\n      <p style=\"font-size:10px;color:#888;margin:8px 0 0\">\ud83d\udd12 R\u00e9servation s\u00e9curis\u00e9e \u00b7 Confirmation imm\u00e9diate \u00b7 Annulation flexible<\/p>\n    <\/td>\n  <\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Par Patrice &amp; Sandra &nbsp;\u00b7&nbsp; G\u00eetes Domaine de la Chapelle &nbsp;\u00b7&nbsp; Roquefort-les-Pins Le vendredi 10 juillet 2026 \u00e0 19h, le Stade Louis-II de Monaco accueille la 40e \u00e9dition du Meeting Herculis EBS \u2014 10e \u00e9tape de la Wanda Diamond League, le circuit d&rsquo;athl\u00e9tisme le plus prestigieux au monde. Class\u00e9 meilleur meeting du monde \u00e0 sept [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26572896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[128],"tags":[541,540,539,537,538],"dipi_cpt_category":[],"class_list":["post-26572894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-cote-azur","tag-athletisme-cote-dazur","tag-evenement-sportif-monaco","tag-ligue-de-diamant-monaco","tag-meeting-herculis-monaco","tag-monaco-juillet-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ligue de Diamant Monaco 2026 : Meeting Herculis<\/title>\n<meta name=\"description\" content=\"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gitesdomainedelachapelle.com\/pt\/ligue-diamant-monaco-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue de Diamant Monaco 2026 : Meeting Herculis\" \/>\n<meta property=\"og:description\" content=\"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/pt\/ligue-diamant-monaco-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00eetes Domaine de la Chapelle\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/patrice.campanella\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T06:15:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T12:25:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1448\" \/>\n\t<meta property=\"og:image:height\" content=\"1086\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Patrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/\"},\"author\":{\"name\":\"Patrice\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\"},\"headline\":\"Ligue de Diamant Monaco 2026 : les stars mondiales de l\u2019athl\u00e9tisme au Stade Louis-II\",\"datePublished\":\"2026-06-01T06:15:51+00:00\",\"dateModified\":\"2026-06-15T12:25:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/\"},\"wordCount\":992,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/meeting-herculis-monaco-2026-ligue-diamant.webp\",\"keywords\":[\"Athl\u00e9tisme C\u00f4te d'Azur\",\"\u00c9v\u00e9nement sportif Monaco\",\"Ligue de Diamant Monaco\",\"Meeting Herculis Monaco\",\"Monaco juillet 2026\"],\"articleSection\":[\"Evenements sur la C\u00f4te d'Azur\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/\",\"name\":\"Ligue de Diamant Monaco 2026 : Meeting Herculis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/meeting-herculis-monaco-2026-ligue-diamant.webp\",\"datePublished\":\"2026-06-01T06:15:51+00:00\",\"dateModified\":\"2026-06-15T12:25:16+00:00\",\"description\":\"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/meeting-herculis-monaco-2026-ligue-diamant.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/meeting-herculis-monaco-2026-ligue-diamant.webp\",\"width\":1448,\"height\":1086,\"caption\":\"Meeting Herculis EBS au Stade Louis-II de Monaco le 10 juillet 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/ligue-diamant-monaco-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue de Diamant Monaco 2026 : les stars mondiales de l\u2019athl\u00e9tisme au Stade Louis-II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"name\":\"Gites Domaine de la Chapelle\",\"description\":\"G\u00eetes de charme avec piscine chauff\u00e9e et jacuzzi privatif sur la C\u00f4te d\u2019Azur\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#organization\",\"name\":\"Gites Domaine de la Chapelle\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unnamed-1.webp\",\"width\":1024,\"height\":1024,\"caption\":\"Gites Domaine de la Chapelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/#\\\/schema\\\/person\\\/820b01290b5b0e5d56db451762c0e004\",\"name\":\"Patrice\",\"pronouns\":\"nous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g\",\"caption\":\"Patrice\"},\"description\":\"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.\",\"sameAs\":[\"https:\\\/\\\/www.gitesdomainedelachapelle.com\",\"https:\\\/\\\/www.facebook.com\\\/patrice.campanella\\\/\",\"https:\\\/\\\/www.instagram.com\\\/piscine_jacuzzi_cotedazur\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/gitesdomainedelachapelle\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gitesdomainedelachapelle\"],\"url\":\"https:\\\/\\\/www.gitesdomainedelachapelle.com\\\/pt\\\/author\\\/patrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ligue de Diamant Monaco 2026 : Meeting Herculis","description":"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/ligue-diamant-monaco-2026\/","og_locale":"pt_PT","og_type":"article","og_title":"Ligue de Diamant Monaco 2026 : Meeting Herculis","og_description":"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.","og_url":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/ligue-diamant-monaco-2026\/","og_site_name":"G\u00eetes Domaine de la Chapelle","article_author":"https:\/\/www.facebook.com\/patrice.campanella\/","article_published_time":"2026-06-01T06:15:51+00:00","article_modified_time":"2026-06-15T12:25:16+00:00","og_image":[{"width":1448,"height":1086,"url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp","type":"image\/webp"}],"author":"Patrice","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Patrice","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#article","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/"},"author":{"name":"Patrice","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004"},"headline":"Ligue de Diamant Monaco 2026 : les stars mondiales de l\u2019athl\u00e9tisme au Stade Louis-II","datePublished":"2026-06-01T06:15:51+00:00","dateModified":"2026-06-15T12:25:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/"},"wordCount":992,"commentCount":0,"publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp","keywords":["Athl\u00e9tisme C\u00f4te d'Azur","\u00c9v\u00e9nement sportif Monaco","Ligue de Diamant Monaco","Meeting Herculis Monaco","Monaco juillet 2026"],"articleSection":["Evenements sur la C\u00f4te d'Azur"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/","name":"Ligue de Diamant Monaco 2026 : Meeting Herculis","isPartOf":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp","datePublished":"2026-06-01T06:15:51+00:00","dateModified":"2026-06-15T12:25:16+00:00","description":"Ligue de Diamant Monaco 2026 : Meeting Herculis au Stade Louis-II le 10 juillet. Les stars mondiales de l\u2019athl\u00e9tisme et billets d\u00e8s 15 \u20ac.","breadcrumb":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#primaryimage","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/meeting-herculis-monaco-2026-ligue-diamant.webp","width":1448,"height":1086,"caption":"Meeting Herculis EBS au Stade Louis-II de Monaco le 10 juillet 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gitesdomainedelachapelle.com\/ligue-diamant-monaco-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gitesdomainedelachapelle.com\/"},{"@type":"ListItem","position":2,"name":"Ligue de Diamant Monaco 2026 : les stars mondiales de l\u2019athl\u00e9tisme au Stade Louis-II"}]},{"@type":"WebSite","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#website","url":"https:\/\/www.gitesdomainedelachapelle.com\/","name":"Gites Domaine de la Chapelle","description":"Alojamentos de charme com piscina aquecida e jacuzzi privado na C\u00f4te d\u2019Azur","publisher":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gitesdomainedelachapelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#organization","name":"Gites Domaine de la Chapelle","url":"https:\/\/www.gitesdomainedelachapelle.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","contentUrl":"https:\/\/www.gitesdomainedelachapelle.com\/wp-content\/uploads\/2026\/06\/unnamed-1.webp","width":1024,"height":1024,"caption":"Gites Domaine de la Chapelle"},"image":{"@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gitesdomainedelachapelle.com\/#\/schema\/person\/820b01290b5b0e5d56db451762c0e004","name":"Patrice","pronouns":"nous","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3f93a01e7806e1fe58fdbecfe9ca6bb725d62824cfd4bcd93ab79fb93dc4f5d?s=96&d=mm&r=g","caption":"Patrice"},"description":"Propri\u00e9taire des G\u00eetes Domaine de la Chapelle, je propose des h\u00e9bergements de charme situ\u00e9s \u00e0 Roquefort-les-Pins, au c\u0153ur de l\u2019arri\u00e8re-pays ni\u00e7ois, entre Nice, Cannes et Grasse, sur la C\u00f4te d\u2019Azur. Nous proposons des locations de vacances haut de gamme, pens\u00e9es pour les couples \u00e0 la recherche d\u2019un s\u00e9jour en amoureux, d\u2019un week-end d\u00e9tente ou de vacances bien-\u00eatre en Provence, avec piscine chauff\u00e9e et jacuzzi privatif, dans un environnement calme, naturel et sans vis-\u00e0-vis. Chaque logement est con\u00e7u pour offrir confort, intimit\u00e9 et qualit\u00e9, avec une attention particuli\u00e8re port\u00e9e \u00e0 l\u2019accueil, aux \u00e9quipements et \u00e0 l\u2019exp\u00e9rience globale du s\u00e9jour. Notre objectif est simple : permettre \u00e0 nos h\u00f4tes de se ressourcer et de profiter pleinement du soleil du Sud, d\u2019un cadre idyllique et des richesses de la C\u00f4te d\u2019Azur.","sameAs":["https:\/\/www.gitesdomainedelachapelle.com","https:\/\/www.facebook.com\/patrice.campanella\/","https:\/\/www.instagram.com\/piscine_jacuzzi_cotedazur\/","https:\/\/www.linkedin.com\/in\/g\u00eetes-domaine-de-la-chapelle-avec-piscine-chauff\u00e9e-et-jacuzzi-privatifs-sur-la-c\u00f4te-d-azur-54053572\/","https:\/\/fr.pinterest.com\/gitesdomainedelachapelle\/","https:\/\/www.youtube.com\/@gitesdomainedelachapelle"],"url":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/author\/patrice\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/comments?post=26572894"}],"version-history":[{"count":3,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572894\/revisions"}],"predecessor-version":[{"id":26573415,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/posts\/26572894\/revisions\/26573415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/media\/26572896"}],"wp:attachment":[{"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/media?parent=26572894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/categories?post=26572894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/tags?post=26572894"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.gitesdomainedelachapelle.com\/pt\/wp-json\/wp\/v2\/dipi_cpt_category?post=26572894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}